{"id":6384,"date":"2020-06-29T18:42:48","date_gmt":"2020-06-29T18:42:48","guid":{"rendered":"https:\/\/teamstone.eu\/loja\/?post_type=product&#038;p=6384"},"modified":"2020-07-01T14:57:37","modified_gmt":"2020-07-01T14:57:37","slug":"chemise-de-nuit-brode-papilon-creme-bleu-creme-saumon-made-in-portugal","status":"publish","type":"product","link":"https:\/\/teamstone.fr\/loja\/product\/chemise-de-nuit-brode-papilon-creme-bleu-creme-saumon-made-in-portugal\/","title":{"rendered":"Chemise de nuit brod\u00e9 papilon, Creme\/Bleu, Creme\/Saumon"},"content":{"rendered":"<p>[vc_row content_placement=&#8221;top&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: left;\">En maille jersey enrichie avec broderie papillons et longue patte de boutonnage, fronces r\u00e9parties sous l&#8217;empi\u00e8cement devant pour une meilleure mobilit\u00e9. La chemise de nuit pr\u00e9sente une encolure ronde, un empi\u00e9cement brod\u00e9 et une patte de boutonage avec 3 boutons, biais \u00e0 la couleur de la broderie. Manches longues avec surpiqure contrast\u00e9, pour une meilleure \u00e9l\u00e9gance. Finitions double piq\u00fbre.<\/p>\n<p style=\"text-align: left;\">Mod\u00e8le con\u00e7u pour offrir bien-\u00eatre et mobilit\u00e9.<\/p>\n<p style=\"text-align: left;\">Contr\u00f4le de confection et qualit\u00e9.<\/p>\n<p style=\"text-align: left;\">Fabriqu\u00e9 au Portugal.<\/p>\n<p style=\"text-align: left;\">Made in Portugal<br \/>\nComposition &amp; Soin:<br \/>\n&#8211; Chemise de nuit\u00a0 en maille jersey<br \/>\n&#8211; Lavable en machine \u00e0 30\u00b0 avec des couleurs similaires<br \/>\n&#8211; Laver et repasser du c\u00f4t\u00e9 envers du produit<br \/>\n&#8211; Ne pas s\u00e9cher au s\u00e8che-linge<br \/>\n&#8211; Repasser \u00e0 basse temp\u00e9rature.<\/p>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<h5 style=\"text-align: center;\"><span style=\"color: #ff6600;\">Action jusqu&#8217;au \u00e9puisement du stock. Quantit\u00e9 limit\u00e9e. Aucune surplus.<\/span><\/h5>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<h6><img loading=\"lazy\" class=\"alignnone wp-image-2914 size-full\" src=\"https:\/\/teamstone.eu\/loja\/wp-content\/uploads\/2017\/06\/reciclavel.png\" alt=\"\" width=\"50\" height=\"47\" \/><strong>Article recyclable; \u00e0 la \u201cfin de la vie&#8221; peut \u00eatre plac\u00e9 \u00e0 un point de collecte<\/strong>.<\/h6>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_id=&#8221;tamanhos&#8221;][vc_column][vc_empty_space height=&#8221;60px&#8221;][vc_tta_accordion style=&#8221;modern&#8221; active_section=&#8221;non-existing number&#8221; collapsible_all=&#8221;true&#8221;][vc_tta_section title=&#8221;Tableau des Tailles&#8221; tab_id=&#8221;1524225399024-c7e87548-dfdd&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Les mesures pr\u00e9sent\u00e9es sont purement indicatives. Prenez vous mesures avec pr\u00e9cision sur vous, et chosissez la taille la plus adapt\u00e9e en consultant le tableau ci-dessus. En cas de doute, choisissez toujours la plus grande taille.<\/p>\n<div class=\"intro\"><\/div>\n<div class=\"guide\">\n<p><a href=\"https:\/\/teamstone.eu\/loja\/wp-content\/uploads\/2018\/08\/tabela-medidas-classico-fr-1.png\"><img loading=\"lazy\" class=\"wp-image-3189 size-full aligncenter\" src=\"https:\/\/teamstone.eu\/loja\/wp-content\/uploads\/2018\/08\/tabela-medidas-classico-fr-1.png\" alt=\"\" width=\"749\" height=\"381\" srcset=\"https:\/\/teamstone.fr\/loja\/wp-content\/uploads\/2018\/08\/tabela-medidas-classico-fr-1.png 749w, https:\/\/teamstone.fr\/loja\/wp-content\/uploads\/2018\/08\/tabela-medidas-classico-fr-1-100x51.png 100w, https:\/\/teamstone.fr\/loja\/wp-content\/uploads\/2018\/08\/tabela-medidas-classico-fr-1-300x153.png 300w, https:\/\/teamstone.fr\/loja\/wp-content\/uploads\/2018\/08\/tabela-medidas-classico-fr-1-600x305.png 600w, https:\/\/teamstone.fr\/loja\/wp-content\/uploads\/2018\/08\/tabela-medidas-classico-fr-1-700x356.png 700w, https:\/\/teamstone.fr\/loja\/wp-content\/uploads\/2018\/08\/tabela-medidas-classico-fr-1-150x76.png 150w\" sizes=\"(max-width: 749px) 100vw, 749px\" \/><\/a><\/p>\n<\/div>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En maille jersey enrichie avec broderie papillons et longue patte de boutonnage, fronces r\u00e9parties sous l&#8217;empi\u00e8cement devant pour une meilleure mobilit\u00e9. La chemise de nuit pr\u00e9sente une encolure ronde, un empi\u00e9cement brod\u00e9 et une patte de boutonage avec 3 boutons, biais \u00e0 la couleur de la broderie. Manches longues avec surpiqure contrast\u00e9, pour une meilleure \u00e9l\u00e9gance<\/p>\n<h5><a href=\"#tamanhos\" rel=\"noopener\"><strong>Voir Tableau des Tailles<\/strong><\/a><\/h5>\n","protected":false},"featured_media":5947,"comment_status":"open","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/teamstone.fr\/loja\/wp-json\/wp\/v2\/product\/6384"}],"collection":[{"href":"https:\/\/teamstone.fr\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/teamstone.fr\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/teamstone.fr\/loja\/wp-json\/wp\/v2\/comments?post=6384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teamstone.fr\/loja\/wp-json\/wp\/v2\/media\/5947"}],"wp:attachment":[{"href":"https:\/\/teamstone.fr\/loja\/wp-json\/wp\/v2\/media?parent=6384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}